{"id":1925,"date":"2014-02-23T10:04:22","date_gmt":"2014-02-23T09:04:22","guid":{"rendered":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/?p=1925"},"modified":"2014-03-02T10:02:25","modified_gmt":"2014-03-02T09:02:25","slug":"desherbant-dorigine-naturelle-et-biodegradable","status":"publish","type":"post","link":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/blog\/2014\/02\/23\/desherbant-dorigine-naturelle-et-biodegradable\/","title":{"rendered":"<strong>D\u00e9sherbant d\u2019origine naturelle et biod\u00e9gradable<\/strong>"},"content":{"rendered":"<p>Suite \u00e0 mon article sur le <a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/blog\/2014\/02\/20\/au-royaume-de-labsurdie-la-guerre-du-purin-dortie-se-poursuit\/\">Purin d\u2019orties <\/a>  et une conversation r\u00e9cente entre amis voici un compl\u00e9ment concernant le d\u00e9sherbage au vinaigre.<\/p>\n<p>Ce que \u00e7a donne avant sur un greffon de vigne :<br \/>\n<a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/02\/D\u00e9sherbant-1.jpg\"><img loading=\"lazy\" src=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/02\/D\u00e9sherbant-1.jpg\" alt=\"D\u00e9sherbant 1\" width=\"333\" height=\"352\" class=\"alignnone size-full wp-image-1926\" srcset=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/02\/D\u00e9sherbant-1.jpg 333w, http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/02\/D\u00e9sherbant-1-283x300.jpg 283w\" sizes=\"(max-width: 333px) 100vw, 333px\" \/><\/a><br \/>\net apr\u00e8s 24 heures (en fait apr\u00e8s 2-3 heures on voit d\u00e9j\u00e0 un d\u00e9but d\u2019action)<br \/>\n<a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/02\/D\u00e9sherbant-2.jpg\"><img loading=\"lazy\" src=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/02\/D\u00e9sherbant-2.jpg\" alt=\"D\u00e9sherbant 2\" width=\"345\" height=\"334\" class=\"alignnone size-full wp-image-1927\" srcset=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/02\/D\u00e9sherbant-2.jpg 345w, http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/02\/D\u00e9sherbant-2-300x290.jpg 300w\" sizes=\"(max-width: 345px) 100vw, 345px\" \/><\/a><\/p>\n<blockquote><p>Mes sources\n<\/p><\/blockquote>\n<p>LETTRE D\u2019INFORMATION DE L\u2019AGENCE R\u00c9GIONALE DE L\u2019ENVIRONNEMENT DE HAUTE-NORMANDIE<br \/>\nPar Jean-Paul Thorez &#8212; Mercredi 4 Septembre 2013<\/p>\n<blockquote><p>Quelques d\u00e9finitions\n<\/p><\/blockquote>\n<p><strong><em>LE VINAIGRE BLANC :<\/em><br \/>\n<\/strong><br \/>\nOui, nous parlons bien de la m\u00eame chose. Le liquide transparent (le fameux \u00ab cristal \u00bb en bouteille plastique) qui sert \u00e0 tout : faire des cornichons, d\u00e9tartrer, nettoyer &#8230;<br \/>\nC\u2019est un m\u00e9lange d\u2019eau (92 %) et d\u2019acide ac\u00e9tique (8 %).<br \/>\nRappelons que l\u2019acide ac\u00e9tique, partie active du vinaigre, est issu de la transformation du sucre par fermentation, c\u2019est-\u00e0-dire par un ph\u00e9nom\u00e8ne biologique naturel mettant en \u0153uvre des bact\u00e9ries. <\/p>\n<p>Le vinaigre est comestible, m\u00eame s\u2019il pique (on dit plut\u00f4t qu\u2019il est irritant pour la peau et les yeux).<br \/>\nIl vaut mieux \u00e9viter d\u2019en avaler une bonne gorg\u00e9e, d\u2019en respirer une bouff\u00e9e, ou d\u2019en mettre au contact des yeux ou des muqueuses. <\/p>\n<p><strong><em>HERBICIDE :<br \/>\n<\/em><\/strong><\/p>\n<p> Ce mot d\u00e9signe toute substance capable de tuer des plantes. On dit aussi \u00ab d\u00e9sherbant \u00bb. <\/p>\n<p>Parmi les herbicides les plus c\u00e9l\u00e8bres figure le <em>\u00ab\u00a0glyphosate\u00a0\u00bb <\/em>(alias Roundup, une des marques commerciales les plus r\u00e9pandues).<br \/>\nCelui-ci a presque le monopole du d\u00e9sherbage \u00ab total \u00bb, diff\u00e9rent du d\u00e9sherbage \u00ab s\u00e9lectif \u00bb en ce sens qu\u2019il n\u2019\u00e9pargne aucune cat\u00e9gorie de plantes (et m\u00eame d&rsquo;\u00eatres vivants).<br \/>\nPourquoi parler du glyphosate dans un article sur le vinaigre ? Tout simplement parce que les deux produits cohabitent maintenant (depuis 2009, plus pr\u00e9cis\u00e9ment) dans la liste officielle des herbicides \u00ab totaux \u00bb utilisables pour le d\u00e9sherbage chimique des all\u00e9es et trottoirs, mais aussi en zone cultiv\u00e9e, avant une mise en culture, ou au pied d\u2019arbres ou d\u2019arbustes. Bravo !<\/p>\n<p>Evidemment, avec du vinaigre comme avec du Roundup, on utilise un pulv\u00e9risateur, et on grille des mauvaises herbes.<br \/>\nMais avec le vinaigre on ne risque pas de s\u2019empoisonner, ni de polluer les nappes phr\u00e9atiques ou les mares voisines ! Un sacr\u00e9 progr\u00e8s tout de m\u00eame. <\/p>\n<p>D\u2019origine naturelle, le vinaigre est biod\u00e9gradable. Compte tenu des doses employ\u00e9es et de la volatilit\u00e9 du produit, son action sur le sol et les \u00eatres vivants qui y vivent semble tr\u00e8s limit\u00e9e. Il ne laisse pas de r\u00e9sidu nocif dans le sol, ni dans les plantes.<br \/>\nD\u2019ailleurs, les plantes sont susceptibles de renfermer de l\u2019acide ac\u00e9tique, et cela le plus naturellement du monde ! <\/p>\n<p><strong>Cependant &#8230;<br \/>\n<\/strong><br \/>\nL\u2019emploi de l\u2019acide ac\u00e9tique est officiellement <em>\u00ab autoris\u00e9 dans les jardins \u00bb. <\/em><br \/>\nMAIS, attention toutefois : l\u2019acide ac\u00e9tique (et donc le vinaigre) n\u2019est pas (encore ?) inscrit dans la liste des produits utilisables en agriculture bio.<br \/>\nC\u2019est pourquoi il ne faut pas parler d\u2019<em>\u00ab herbicide bio \u00bb. <\/em><\/p>\n<p>Pour en savoir plus : <\/p>\n<p>Cherchez l\u2019acide ac\u00e9tique dans <a href=\"http:\/\/e-phy.agriculture.gouv.fr\/ \">la liste alphab\u00e9tique des substances<\/a>.<br \/>\nVous verrez que l\u2019acide ac\u00e9tique entre dans la composition d\u2019herbicides du commerce, avec un dosage de 10 %. Le vinaigre blanc du commerce ne dose que 8 % d\u2019acide ac\u00e9tique, mais il est \u00e9galement efficace. On trouve du 10% et m\u00eame 14% dans les magasin de bricolage.<\/p>\n<blockquote><p>Mode d\u2019emploi<\/p><\/blockquote>\n<p>On applique 100 ml de produit dos\u00e9 \u00e0 10 % d\u2019acide ac\u00e9tique par m\u00e8tre carr\u00e9, soit 0,1 litre par m\u00e8tre carr\u00e9, ou encore 1 litre pour 10 m2. <\/p>\n<p>En remplissant la cuve d\u2019un pulv\u00e9risateur de 5 litres, vous avez donc de quoi traiter 50 m2, c\u2019est-\u00e0-dire, par exemple, un rectangle de terrain de 10 m\u00e8tres par 5. <\/p>\n<p>Avec notre vinaigre du commerce dos\u00e9 \u00e0 8 %, on traite un peu moins de surface avec le m\u00eame volume, c\u2019est-\u00e0-dire 40 m2.<br \/>\nCe traitement aura co\u00fbt\u00e9 environ 2,50 \u20ac (prix en conditionnement de 10 litres), ce qui est relativement modique.<\/p>\n<p>Appliquez le vinaigre pur, par temps ensoleill\u00e9, \u00e0 l\u2019aide d\u2019un pulv\u00e9risateur. Rincez ensuite celui-ci.<\/p>\n<p>L\u2019effet est quasi imm\u00e9diat. Les feuilles des herbes grillent, en commen\u00e7ant par les plus larges. Les tr\u00e8s jeunes plantes sont d\u00e9truites. S\u2019il pleut ensuite, il peut y avoir une repousse, notamment des grosses plantes pourvues d\u2019une racine profonde. Mais la v\u00e9g\u00e9tation en place reste \u00ab d\u00e9prim\u00e9e \u00bb pendant plus d\u2019un an. On peut r\u00e9p\u00e9ter le traitement jusqu\u2019\u00e0 6 fois par an pour am\u00e9liorer l\u2019efficacit\u00e9. <\/p>\n<p>________________________________________________________________________________<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suite \u00e0 mon article sur le Purin d\u2019orties et une conversation r\u00e9cente entre amis voici un compl\u00e9ment concernant le d\u00e9sherbage au vinaigre. Ce que \u00e7a donne avant sur un greffon de vigne : et apr\u00e8s 24 heures (en fait apr\u00e8s 2-3 heures on voit d\u00e9j\u00e0 un d\u00e9but d\u2019action) Mes sources LETTRE D\u2019INFORMATION DE L\u2019AGENCE R\u00c9GIONALE DE L\u2019ENVIRONNEMENT DE HAUTE-NORMANDIE Par Jean-Paul Thorez &#8212; Mercredi 4 Septembre 2013 Quelques d\u00e9finitions LE VINAIGRE BLANC : Oui, nous parlons bien de la m\u00eame chose. Le liquide transparent (le fameux \u00ab cristal \u00bb en bouteille plastique) qui sert \u00e0 tout : faire des cornichons, d\u00e9tartrer, nettoyer &#8230; C\u2019est un m\u00e9lange d\u2019eau (92 %) et d\u2019acide ac\u00e9tique (8 %). Rappelons que l\u2019acide ac\u00e9tique, partie active du vinaigre, est issu de la transformation du sucre par fermentation, c\u2019est-\u00e0-dire par un ph\u00e9nom\u00e8ne biologique naturel mettant en \u0153uvre des bact\u00e9ries. Le vinaigre est comestible, m\u00eame s\u2019il pique (on dit plut\u00f4t qu\u2019il est irritant pour la peau et les yeux). Il vaut mieux \u00e9viter d\u2019en avaler une bonne gorg\u00e9e, d\u2019en respirer une bouff\u00e9e, ou d\u2019en mettre au contact des yeux ou des muqueuses. HERBICIDE : Ce mot d\u00e9signe toute substance capable de tuer des plantes. On dit aussi \u00ab [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/1925"}],"collection":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/comments?post=1925"}],"version-history":[{"count":3,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/1925\/revisions"}],"predecessor-version":[{"id":1968,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/1925\/revisions\/1968"}],"wp:attachment":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/media?parent=1925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/categories?post=1925"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/tags?post=1925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}