{"id":3073,"date":"2014-09-24T10:44:13","date_gmt":"2014-09-24T08:44:13","guid":{"rendered":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/?p=3073"},"modified":"2014-09-24T10:44:13","modified_gmt":"2014-09-24T08:44:13","slug":"danone-oblige-de-retirer-sa-publicite-mensongere-apres-15-annees-de-matraquage-et-de-degats","status":"publish","type":"post","link":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/blog\/2014\/09\/24\/danone-oblige-de-retirer-sa-publicite-mensongere-apres-15-annees-de-matraquage-et-de-degats\/","title":{"rendered":"<strong>Danone oblig\u00e9 de retirer sa publicit\u00e9 mensong\u00e8re apr\u00e8s 15 ann\u00e9es de matraquage et de d\u00e9g\u00e2ts<\/strong>"},"content":{"rendered":"<p><a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/09\/Activia.jpg\"><img loading=\"lazy\" src=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/09\/Activia.jpg\" alt=\"Activia\" width=\"588\" height=\"315\" class=\"alignnone size-full wp-image-3074\" srcset=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/09\/Activia.jpg 588w, http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/09\/Activia-300x160.jpg 300w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><\/a><br \/>\nJ\u2019en avais parl\u00e9 en d\u00e9but d\u2019ann\u00e9e voir ce lien :<br \/>\n<a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/blog\/2014\/02\/07\/actimel-calin-and-co-stop-a-larnaque\/\">Actimel, C\u00e2lin and Co<\/a> <\/p>\n<h1>APR\u00c8S 15 ANS DE MATRAQUAGE ET DE D\u00c9G\u00c2TS AVEC LES YAOURTS \u00ab ACTIVIA \u00bb ET \u00ab ACTIMEL \u00bb : DANONE OBLIG\u00c9 DE RETIRER SA PUBLICIT\u00c9.<\/h1>\n<p> Danone avait oubli\u00e9 de nous dire que ses yaourts \u00e9taient destin\u00e9s aux sujets anorexiques.<\/p>\n<p>Le <em>\u00ab pav\u00e9 dans le pot de yaourt \u00bb<\/em> qu\u2019a lanc\u00e9 Didier Raoult, chercheur fran\u00e7ais, dans la prestigieuse revue scientifique Nature de septembre 2009 a fini par \u00eatre payant.<\/p>\n<p>Pour le patron du labo de virologie de la Timone, \u00e0 Marseille, les yaourts et autres boissons lact\u00e9es farcis aux probiotiques que l\u2019on nous fait avaler depuis pr\u00e8s de 20 ans auraient une grosse part de responsabilit\u00e9 dans l\u2019\u00e9pid\u00e9mie d\u2019ob\u00e9sit\u00e9 qui frappe les enfants.<\/p>\n<p>Les probiotiques que Danone ajoute \u00e0 tout va dans divers yaourts sont, selon les all\u00e9gations de la marque ass\u00e9n\u00e9es \u00e0 la t\u00e9l\u00e9vision, cens\u00e9es booster les d\u00e9fenses immunitaires. On en trouve plus d\u20191 milliard par pot d\u2019Activia ou d\u2019Actimel.<\/p>\n<p>Le hic, c\u2019est que ces bonnes bact\u00e9ries <em>\u00ab actives et vivantes \u00bb, <\/em>dixit Danone, sont les m\u00eames que celles utilis\u00e9es depuis longtemps dans les \u00e9levages industriels comme activateurs de croissance pour faire grossir plus rapidement cochons et poulets. Un porc ainsi gav\u00e9 de probiotiques, c\u2019est plus de 10 % de gagn\u00e9 sur la balance. Danone pousse donc \u00e0 \u00ab \u00e9lever \u00bb nos enfants comme des cochons ou des poulets !<\/p>\n<p>En fait, en d\u00e9but d\u2019ann\u00e9e, des chercheurs ont eu l\u2019id\u00e9e de comparer la flore intestinale des ob\u00e8ses et des non-ob\u00e8ses. Et l\u00e0, surprise, les premiers \u00e9taient bourr\u00e9s de probiotiques, ceux qu\u2019on trouve justement dans les yaourts \u00ab sant\u00e9 plus \u00bb.<\/p>\n<blockquote><p>Didier Raoult commente :\n<\/p><\/blockquote>\n<p><em>\u00ab\u00a0On a autoris\u00e9 pour l\u2019alimentation humaine des activateurs de croissance utilis\u00e9s dans les \u00e9levages, sans chercher \u00e0 savoir quel serait l\u2019effet sur les enfants<br \/>\nDu coup, celui-ci a r\u00e9clam\u00e9 des \u00e9tudes pour conna\u00eetre le r\u00f4le pr\u00e9cis de TOUS les produits lact\u00e9s dans l\u2019\u00e9pid\u00e9mie d\u2019ob\u00e9sit\u00e9 infantile. En outre, il n y a pas que les enfants qui sont victimes de cette supercherie : \u00ab J\u2019ai rencontr\u00e9 de nombreuses femmes potel\u00e9es bien que sous aliment\u00e9es, et qui cherchaient d\u00e9sesp\u00e9r\u00e9ment \u00e0 maigrir en se limitant \u00e0 quelques yaourts par jour plus quelques babioles \u00bb. Et d\u00e9sesp\u00e9rante d\u00e9sillusion, elles continuaient \u00e0 grossir, \u00e9taient de plus en plus fatigu\u00e9es et fragiles&#8230;\u00a0\u00bb<\/em><\/p>\n<p>Finalement, les semeurs d\u2019alerte ind\u00e9pendants ont fini par \u00e9mouvoir les services officiels avant que le scandale n\u2019\u00e9clate trop au grand jour. C\u2019est ainsi qu\u2019ils viennent de mettre la pression sur le groupe Danone, l\u2019obligeant, selon les termes d\u00e9licats des grands journaux <em>\u00ab \u00e0 revoir sa copie \u00bb<\/em> (un monstre comme Danone, \u00e7a se m\u00e9nage).<br \/>\nIl faut tout de m\u00eame r\u00e9aliser que cela pourrait \u00eatre un coup dur pour le lobby, puisque les groupes Actimel Europe et Activia Europe p\u00e8sent ensemble plus de 1,5 milliards d\u2019euros sur un chiffre total Danone de 15 milliards, soit 10 %. Mais ne nous faisons gu\u00e8re de soucis pour cette entreprise de tricheurs, car entre ses discr\u00e8tes et adroites man\u0153uvres de retrait publicitaires et les addictions de beaucoup de consommateurs, il n\u2019y a pas vraiment le \u00ab feu au lac \u00bb, en attendant qu\u2019on nous invente une autre \u00ab salade \u00e0 la mode \u00bb.<\/p>\n<p><a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/09\/Activia1.jpg\"><img loading=\"lazy\" src=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2014\/09\/Activia1.jpg\" alt=\"Activia1\" width=\"94\" height=\"150\" class=\"alignnone size-full wp-image-3075\" \/><\/a><br \/>\nDidier Raoult est professeur de microbiologie et sp\u00e9cialiste des maladies infectieuses. Il dirige l\u2019Unit\u00e9 de Recherche en Maladies Infectieuses et Tropicales \u00c9mergentes (URMITE) de Marseille. Le Grand Prix Inserm 2010 lui a \u00e9t\u00e9 d\u00e9cern\u00e9 \u00e0 58 ans pour l\u2019ensemble de ses travaux sur les agents pathog\u00e8nes et sa d\u00e9couverte des virus g\u00e9ants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u2019en avais parl\u00e9 en d\u00e9but d\u2019ann\u00e9e voir ce lien : Actimel, C\u00e2lin and Co APR\u00c8S 15 ANS DE MATRAQUAGE ET DE D\u00c9G\u00c2TS AVEC LES YAOURTS \u00ab ACTIVIA \u00bb ET \u00ab ACTIMEL \u00bb : DANONE OBLIG\u00c9 DE RETIRER SA PUBLICIT\u00c9. Danone avait oubli\u00e9 de nous dire que ses yaourts \u00e9taient destin\u00e9s aux sujets anorexiques. Le \u00ab pav\u00e9 dans le pot de yaourt \u00bb qu\u2019a lanc\u00e9 Didier Raoult, chercheur fran\u00e7ais, dans la prestigieuse revue scientifique Nature de septembre 2009 a fini par \u00eatre payant. Pour le patron du labo de virologie de la Timone, \u00e0 Marseille, les yaourts et autres boissons lact\u00e9es farcis aux probiotiques que l\u2019on nous fait avaler depuis pr\u00e8s de 20 ans auraient une grosse part de responsabilit\u00e9 dans l\u2019\u00e9pid\u00e9mie d\u2019ob\u00e9sit\u00e9 qui frappe les enfants. Les probiotiques que Danone ajoute \u00e0 tout va dans divers yaourts sont, selon les all\u00e9gations de la marque ass\u00e9n\u00e9es \u00e0 la t\u00e9l\u00e9vision, cens\u00e9es booster les d\u00e9fenses immunitaires. On en trouve plus d\u20191 milliard par pot d\u2019Activia ou d\u2019Actimel. Le hic, c\u2019est que ces bonnes bact\u00e9ries \u00ab actives et vivantes \u00bb, dixit Danone, sont les m\u00eames que celles utilis\u00e9es depuis longtemps dans les \u00e9levages industriels comme activateurs de croissance pour faire grossir plus rapidement cochons [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"_links":{"self":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/3073"}],"collection":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/comments?post=3073"}],"version-history":[{"count":1,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/3073\/revisions"}],"predecessor-version":[{"id":3076,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/3073\/revisions\/3076"}],"wp:attachment":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/media?parent=3073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/categories?post=3073"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/tags?post=3073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}