{"id":5348,"date":"2016-02-02T11:29:40","date_gmt":"2016-02-02T10:29:40","guid":{"rendered":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/?p=5348"},"modified":"2016-02-02T11:30:56","modified_gmt":"2016-02-02T10:30:56","slug":"apres-avoir-pille-le-tiers-monde-les-occidentaux-en-sont-reduits-a-se-piller-eux-memes","status":"publish","type":"post","link":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/blog\/2016\/02\/02\/apres-avoir-pille-le-tiers-monde-les-occidentaux-en-sont-reduits-a-se-piller-eux-memes\/","title":{"rendered":"Apr\u00e8s avoir pill\u00e9 le tiers monde, les occidentaux en sont r\u00e9duits \u00e0 se piller eux-m\u00eames !"},"content":{"rendered":"<p><a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/02\/Pillage.jpg\" rel=\"attachment wp-att-5349\"><img loading=\"lazy\" src=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/02\/Pillage.jpg\" alt=\"Pillage\" width=\"600\" height=\"297\" class=\"alignnone size-full wp-image-5349\" srcset=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/02\/Pillage.jpg 600w, http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/02\/Pillage-300x149.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<h1>Paul Craig Roberts<\/h1>\n<p>Paul Craig Roberts est un \u00e9conomiste et journaliste am\u00e9ricain, n\u00e9 le 3 avril 1939 \u00e0 Atlanta (G\u00e9orgie).<br \/>\nTitulaire d&rsquo;un doctorat obtenu \u00e0 l&rsquo;Universit\u00e9 de Virginie, il est dipl\u00f4m\u00e9 de l&rsquo;Institut de technologie de G\u00e9orgie, de l&rsquo;Universit\u00e9 de Californie (Berkeley) et de l&rsquo;Universit\u00e9 d&rsquo;Oxford, o\u00f9 il a \u00e9t\u00e9 membre du Merton Coll\u00e8ge.<\/p>\n<h2>Citations<\/h2>\n<blockquote><p>\u00ab Le gouvernement des Etats-Unis est l&rsquo;organisation criminelle la plus achev\u00e9e de l&rsquo;histoire humaine. \u00bb<\/p>\n<p>\u00ab Comme me l&rsquo;a dit une fois un sous-secr\u00e9taire d&rsquo;\u00e9tat \u00e0 la D\u00e9fense, \u00ab\u00a0Les gouvernements europ\u00e9ens sont \u00e0 nos ordres. Nous les payons, et nous en sommes propri\u00e9taires.\u00a0\u00bb \u00bb\n<\/p><\/blockquote>\n<h1>Article de Craig Roberts<\/h1>\n<p>Michael Hudson, John Perkins et moi-m\u00eame ainsi que quelques autres avons rapport\u00e9 le pillage multi-facettes des peuples par les institutions \u00e9conomiques occidentales, principalement les grandes banques de New York avec l\u2019aide de FMI.<\/p>\n<p>Les pays du tiers monde ont \u00e9t\u00e9 et sont toujours pill\u00e9s en \u00e9tant incit\u00e9s et forc\u00e9s \u00e0 suivre des plans de d\u00e9veloppement pour l\u2019\u00e9lectrification ou autres objectifs. Les gouvernements de ces pays, na\u00effs et confiants, sont endoctrin\u00e9s \u00e0 croire qu\u2019ils peuvent faire de leurs pays des nations riches en prenant les pr\u00eats bancaires pr\u00e9sent\u00e9s pour mettre en place les plans de d\u00e9veloppement pr\u00e9par\u00e9s par l\u2019occident, ayant pour r\u00e9sultat de suffisants revenus fiscaux du d\u00e9veloppement \u00e9conomique pour rembourser les emprunts \u00e9trangers.<\/p>\n<p>Cela bien s\u00fbr n\u2019arrive jamais ou pratiquement jamais. Ce qu\u2019il se passe est que le plan a pour r\u00e9sultat que le pays devient endett\u00e9 bien au-del\u00e0 de ses revenus en devises \u00e9trang\u00e8res et lorsque le pays ne peut plus honorer le remboursement de sa dette pour d\u00e9veloppement. Les cr\u00e9diteurs envoient alors le FMI dire au gouvernement endett\u00e9 que le FMI prot\u00e8gera son cr\u00e9dit en lui pr\u00eatant de l\u2019argent pour rembourser ses banquiers cr\u00e9diteurs. Mais les conditions font que ce gouvernement prenne les mesures d\u2019aust\u00e9rit\u00e9 n\u00e9cessaires de fa\u00e7on \u00e0 ce qu\u2019il puisse aussi rembourser le FMI (NdT: le pi\u00e8ge classique d\u2019emprunter pour rembourser un emprunt, quand on en est l\u00e0, c\u2019est la fin des haricots\u2026). Ces mesures d\u2019aust\u00e9rit\u00e9 doivent museler les d\u00e9penses des services publics et du secteur gouvernemental, r\u00e9duire les retraites publiques, et vendre les ressources nationales aux \u00e9trangers acheteurs. <\/p>\n<p>L\u2019argent \u00e9conomis\u00e9 en r\u00e9duisant les fonds sociaux et r\u00e9colt\u00e9 en vendant les biens nationaux \u00e0 des \u00e9trangers sert \u00e0 rembourser le FMI. (NdT: exemples typiques, l\u2019Argentine et en Europe bien s\u00fbr la Gr\u00e8ce\u2026)<br \/>\n[ \u2026 ]<\/p>\n<p>Pour lire la suite cliquez ce titre : <a href=\"https:\/\/resistance71.wordpress.com\/2016\/02\/01\/resistance-politique-echec-et-effondrement-attendent-la-civilisation-occidentale-paul-craig-roberts\/\">L\u2019occident en est r\u00e9duit \u00e0 se piller lui-m\u00eame<\/a><\/p>\n<p>L\u2019article original en anglais cliquez ici <a href=\"http:\/\/www.paulcraigroberts.org\/2016\/01\/30\/the-west-is-reduced-to-looting-itself-paul-craig-roberts\/\"> The West Is Reduced To Looting Itself \u2014 Paul Craig Roberts<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paul Craig Roberts Paul Craig Roberts est un \u00e9conomiste et journaliste am\u00e9ricain, n\u00e9 le 3 avril 1939 \u00e0 Atlanta (G\u00e9orgie). Titulaire d&rsquo;un doctorat obtenu \u00e0 l&rsquo;Universit\u00e9 de Virginie, il est dipl\u00f4m\u00e9 de l&rsquo;Institut de technologie de G\u00e9orgie, de l&rsquo;Universit\u00e9 de Californie (Berkeley) et de l&rsquo;Universit\u00e9 d&rsquo;Oxford, o\u00f9 il a \u00e9t\u00e9 membre du Merton Coll\u00e8ge. Citations \u00ab Le gouvernement des Etats-Unis est l&rsquo;organisation criminelle la plus achev\u00e9e de l&rsquo;histoire humaine. \u00bb \u00ab Comme me l&rsquo;a dit une fois un sous-secr\u00e9taire d&rsquo;\u00e9tat \u00e0 la D\u00e9fense, \u00ab\u00a0Les gouvernements europ\u00e9ens sont \u00e0 nos ordres. Nous les payons, et nous en sommes propri\u00e9taires.\u00a0\u00bb \u00bb Article de Craig Roberts Michael Hudson, John Perkins et moi-m\u00eame ainsi que quelques autres avons rapport\u00e9 le pillage multi-facettes des peuples par les institutions \u00e9conomiques occidentales, principalement les grandes banques de New York avec l\u2019aide de FMI. Les pays du tiers monde ont \u00e9t\u00e9 et sont toujours pill\u00e9s en \u00e9tant incit\u00e9s et forc\u00e9s \u00e0 suivre des plans de d\u00e9veloppement pour l\u2019\u00e9lectrification ou autres objectifs. Les gouvernements de ces pays, na\u00effs et confiants, sont endoctrin\u00e9s \u00e0 croire qu\u2019ils peuvent faire de leurs pays des nations riches en prenant les pr\u00eats bancaires pr\u00e9sent\u00e9s pour mettre en place les plans de d\u00e9veloppement pr\u00e9par\u00e9s par [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/5348"}],"collection":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/comments?post=5348"}],"version-history":[{"count":1,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/5348\/revisions"}],"predecessor-version":[{"id":5350,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/5348\/revisions\/5350"}],"wp:attachment":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/media?parent=5348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/categories?post=5348"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/tags?post=5348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}