{"id":6258,"date":"2017-03-18T14:57:41","date_gmt":"2017-03-18T13:57:41","guid":{"rendered":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/?p=6258"},"modified":"2017-04-26T17:06:47","modified_gmt":"2017-04-26T15:06:47","slug":"qui-ne-connait-pas-jean-lassalle-candidat-a-la-presidentielle","status":"publish","type":"post","link":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/blog\/2017\/03\/18\/qui-ne-connait-pas-jean-lassalle-candidat-a-la-presidentielle\/","title":{"rendered":"Qui ne conna\u00eet pas Jean Lassalle, candidat \u00e0 la pr\u00e9sidentielle ?"},"content":{"rendered":"<p><a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle.jpg\"><img loading=\"lazy\" src=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle.jpg\" alt=\"\" width=\"638\" height=\"417\" class=\"alignnone size-full wp-image-6259\" srcset=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle.jpg 638w, http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle-300x196.jpg 300w, http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle-184x120.jpg 184w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/a><br \/>\nSource Ouest France<\/p>\n<h1>Le d\u00e9put\u00e9 des Pyr\u00e9n\u00e9es-Atlantiques ex-Modem Jean Lassalle, <\/h1>\n<p>61 ans, marcheur, chanteur, provocateur, sans \u00e9tiquette politique et sans argent, a obtenu ses 500 signatures pour \u00eatre au premier tour de la pr\u00e9sidence de la R\u00e9publique.<\/p>\n<p>Avec l\u2019accent rocailleux de son B\u00e9arn natal, il annon\u00e7ait, le 17 mars 2016\u2009: \u00ab\u2009Je veux \u00eatre un candidat populaire qui est l\u00e0 pour retaper la France, pour aller vers le peuple.\u2009\u00bb Jean Lassalle, il y a un an d\u00e9j\u00e0, professait que les 500 signatures ne seraient \u00ab\u2009pas un probl\u00e8me\u2009\u00bb. Et il les a eues, comme l&rsquo;a confirm\u00e9 samedi 18 mars le Conseil constitutionnel. En octobre 2016, Jean Lassalle sort un livre programme Un berger \u00e0 l\u2019Elys\u00e9e. Programm\u00e9 depuis son enfance, son chemin politique est pour lui une \u00e9vidence.<\/p>\n<p>\u00ab\u2009Je n\u2019ai pas un sou, mais si les gens croient en moi, je trouverai de l\u2019argent.\u2009\u00bb Sans \u00e9tiquette depuis son d\u00e9part du MoDem en 2016, o\u00f9 il est rest\u00e9 pr\u00e8s de 10 ans, il a l\u2019intention de cr\u00e9er un parti. \u00ab\u2009Le nom, je le trouverai avec le peuple\u2009\u00bb. <\/p>\n<p>\u00ab\u2009Mon r\u00eave c\u2019\u00e9tait d\u2019\u00eatre rugbymen.\u2009\u00bb Du haut de son 1,92\u2009m, Jean Lassalle en impose. Le rugby, il l\u2019a dans la carrure, le nez \u00e0 la Depardieu et surtout dans les veines. Il a transmis sa passion \u00e0 ses trois fils. Thibault, l\u2019a\u00een\u00e9 est pro dans l\u2019\u00e9quipe de Castres olympique\u2009: \u00ab\u2009Mon p\u00e8re Pr\u00e9sident, \u00e7a ne me fait pas r\u00eaver. Mais, ce n\u2019est pas une surprise. Il est si d\u00e9termin\u00e9.\u2009\u00bb<br \/>\n<a href=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle2.jpg\"><img loading=\"lazy\" src=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle2.jpg\" alt=\"\" width=\"640\" height=\"427\" class=\"alignnone size-full wp-image-6260\" srcset=\"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle2.jpg 640w, http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle2-300x200.jpg 300w, http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/03\/J.-Lassalle2-180x120.jpg 180w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nJean Lassalle, en f\u00e9vrier 2017, \u00e0 Paris. | AFP<\/p>\n<h1>\u00ab\u2009Une force de la nature\u2009\u00bb<\/h1>\n<p>L\u2019an dernier, Ouest-France le rencontrait \u00e0 l\u2019Assembl\u00e9e nationale o\u00f9 il si\u00e8ge depuis 2007. Ce qui frappe: ses mains, \u00e9normes, ab\u00eem\u00e9es par les travaux de la terre. \u00ab\u2009J\u2019aime d\u00e9broussailler, me servir de ma moto bineuse, me confronter \u00e0 la terre\u2009\u00bb, affirme l\u2019ancien berger. Il y trouve la s\u00e9r\u00e9nit\u00e9, \u00ab\u2009un moment pour r\u00e9fl\u00e9chir\u2009\u00bb.<\/p>\n<p>Le montagnard est n\u00e9 le 3 mai 1955, \u00e0 Lourdios-Ich\u00e8re. \u00ab\u2009Ma maison, c\u2019est dans la montagne. Le village est loin de tout.\u2009\u00bb Une enfance sereine, chantante mais tr\u00e8s modeste, dans une famille de bergers transhumants, sa m\u00e8re est communiste et son p\u00e8re gaulliste. Avec ses deux s\u0153urs et son fr\u00e8re, il a l\u2019habitude de c\u00f4toyer des objecteurs de conscience \u00e0 la bergerie. Il \u00e9coute les paroles de ces hommes. Il sympathise.<\/p>\n<p>Bernard Bourguinat, l\u2019un d\u2019eux, se souvient\u2009: \u00ab\u2009Jean avait une maturit\u00e9 pr\u00e9coce. Il souffrait du regard des enfants du village.\u2009\u00bb Chaque jour, pour aller \u00e0 l\u2019\u00e9cole, il descend de la montagne par les chemins. Pas de routes. Il se le promet\u2009: \u00ab\u2009Un jour, je serai le maire. Je ferai une route.\u2009\u00bb Et il n\u2019a pas de doutes\u2026<\/p>\n<p>\u00ab\u2009C\u2019est une force de la nature\u2009\u00bb, affirme son ami d\u2019enfance, Didier Herv\u00e9. \u00c0 14 ans, ils \u00e9taient ensemble au lyc\u00e9e agricole. \u00ab\u2009Introverti, il regardait toujours par la fen\u00eatre.\u2009\u00bb Mais, c\u2019\u00e9tait au d\u00e9but. \u00ab\u2009Il a fini animateur des soir\u00e9es du lyc\u00e9e.\u2009\u00bb Jean Lassalle confirme\u2009: \u00ab\u2009Au lyc\u00e9e, j\u2019avais des boutons, les cheveux longs, j\u2019\u00e9tais grand et d\u00e9gingand\u00e9, je n\u2019\u00e9tais pas tr\u00e8s beau.\u2009\u00bb<\/p>\n<h1>Les mandats s\u2019encha\u00eenent<\/h1>\n<p>L\u2019admirateur de De Gaulle et de Gandhi est \u00e9lu maire de Lourdios-Ich\u00e8re, dans la vall\u00e9e d\u2019Aspe, le 20 mars 1977. Il a 21 ans. \u00ab\u2009Comme mon p\u00e8re, j\u2019\u00e9tais berger. Mais la politique a \u00e9t\u00e9 plus forte.\u2009\u00bb C\u2019est son fr\u00e8re cadet Julien qui reprend le troupeau.<\/p>\n<p>Jean Lassalle a \u00ab\u2009le d\u00e9sir de convaincre\u2009\u00bb. Les mandats s\u2019encha\u00eenent\u2009: conseiller g\u00e9n\u00e9ral de 1982 \u00e0 2015, \u00e9lu au Parlement de Navarre (Pau) et d\u00e9put\u00e9 depuis 2002, et m\u00eame pr\u00e9sident de l\u2019Association des populations des montagnes et du monde (APMM).<br \/>\n\u00c0 23 ans, en bo\u00eete, sur les Champs-\u00c9lys\u00e9es, \u00e0 Paris, il a rencontr\u00e9 Pascale. Elle est devenue sa femme et la m\u00e8re de leurs quatre enfants. Elle n\u2019est jamais tr\u00e8s loin. Son mari Pr\u00e9sident, elle ne se voit pas habiter \u00e0 l\u2019\u00c9lys\u00e9e\u2009: \u00ab\u2009Je resterai \u00e0 Lourdios-Ich\u00e8re, il fera son travail.\u2009\u00bb<\/p>\n<h1>Actions atypiques<\/h1>\n<p>Lysiane Palacin, sa collaboratrice parlementaire, le d\u00e9crit comme \u00ab\u2009un homme de caract\u00e8re, au parler vrai, un homme de combat\u2009\u00bb. Il se d\u00e9marque par des actions atypiques. Le 3 juin 2003, droit comme un I, il entonne le Si Canti, un chant de son enfance, pour contrer Nicolas Sarkozy \u00e0 l\u2019Assembl\u00e9e nationale. Il veut se faire entendre\u2009: \u00ab\u2009Lorsque tout a \u00e9t\u00e9 essay\u00e9, il reste le chant.\u2009\u00bb Jean Lassalle est aussi un m\u00e9lomane admirateur de Vivaldi.<\/p>\n<p>En 2006, il s\u2019engage dans une gr\u00e8ve de la faim contre la d\u00e9localisation d\u2019une usine. Ces 39 jours ont laiss\u00e9 des traces sur la sant\u00e9 du candidat. \u00ab\u2009J\u2019ai r\u00e9ussi \u00e0 maintenir environ 140 emplois\u2009\u00bb, se r\u00e9jouit-il. L\u2019usine tourne toujours, il a perdu 21\u2009kg.<\/p>\n<p>Aux \u00e9lections r\u00e9gionales en 2010, il fait le buzz avec son slogan \u00ab\u2009Vous ne le savez pas encore, mais vous allez voter pour moi.\u2009\u00bb Il fait 16\u2009%. \u00ab\u2009Il avait transform\u00e9 l\u2019essai\u2009\u00bb, s\u2019amuse Bernard Bourguinat. Jean Lassalle croit en sa \u00ab\u2009bonne \u00e9toile\u2009\u00bb.<\/p>\n<h1>\u00ab\u2009Parti seul en croisade\u2009\u00bb<\/h1>\n<p>Il a \u00e9t\u00e9 \u00e9vinc\u00e9 aux derni\u00e8res r\u00e9gionales et son amiti\u00e9 de 40 ans avec Fran\u00e7ois Bayrou est en berne. Jean Lassalle est depuis \u00ab\u2009parti seul en croisade\u2009\u00bb, tandis que Fran\u00e7ois Bayrou a fait alliance avec Emmanuel Macron, qui a aussi approch\u00e9 le d\u00e9put\u00e9 des Pyr\u00e9n\u00e9es-Atlantiques par SMS, selon lui.<br \/>\nEn 2013, le d\u00e9put\u00e9 fait un tour de France \u00e0 pieds\u2009\u2013\u2009une \u00ab\u2009promenade\u2009\u00bb de plus de 5\u2009000 kilom\u00e8tres qui a dur\u00e9 8 mois et qui a n\u00e9cessit\u00e9 un emprunt \u00e0 la banque. Jean Lassalle s\u2019excuse presque\u2009: \u00ab\u2009Pascale a d\u00fb vendre son \u00e9levage de porcs de montagne pour tenir.\u2009\u00bb<\/p>\n<p>Lors de ce tour tr\u00e8s m\u00e9diatis\u00e9, il est all\u00e9 \u00e0 la rencontre \u00ab\u2009du peuple fran\u00e7ais\u2009\u00bb, \u00e9couter, recueillir. \u00ab\u2009Je suis le candidat qui conna\u00eet le mieux la France\u2009\u00bb, mart\u00e8le-t-il.<br \/>\nSon cheval de bataille, ce sont les \u00e9nergies renouvelables. \u00ab\u2009Les mar\u00e9es de la fa\u00e7ade maritime et le soleil, c\u2019est \u00e7a l\u2019avenir.\u2009\u00bb Il s\u2019emporte \u00e0 l\u2019\u00e9vocation du p\u00e9trole. Il insiste\u2009: \u00ab\u2009Sauver l\u2019Afrique, c\u2019est aider cette population \u00e0 apprivoiser le soleil.\u2009\u00bb Son programme se fera avec l\u2019Afrique. Bernard Bourguinat l\u2019affirme\u2009: \u00ab\u2009Il ira jusqu\u2019au bout.\u2009\u00bb<\/p>\n<h1>Parti voir Bachar al-Assad en janvier<\/h1>\n<p>S\u2019il est \u00e9lu, il promet \u00ab\u2009de rassembler ce grand peuple qui est le n\u00f4tre, qui est divis\u00e9 et d\u00e9sesp\u00e9r\u00e9\u2009\u00bb. Il veut lutter contre \u00ab\u2009un syst\u00e8me purement sp\u00e9culatif et lib\u00e9rer les gens de l\u2019oppression financi\u00e8re\u2009\u00bb. Sans vouloir sortir de l&rsquo;Union europ\u00e9enne, il entend n\u00e9gocier des \u00ab\u2009marges de man\u0153uvre\u2009\u00bb.<br \/>\nJean Lassalle entend passer aux \u00e9nergies renouvelables \u00ab\u2009car on va bient\u00f4t sortir du p\u00e9trole\u2009\u00bb. Il retirera imm\u00e9diatement \u00ab\u2009nos troupes du Proche-Orient o\u00f9 on tire sur des amis\u2009\u00bb. En janvier dernier, Thierry Mariani, Nicolas Dhuicq (LR) et lui se sont rendus \u00e0 Damas pour discuter avec Bachar al-Assad. \u00ab\u2009Je suis dans l\u2019incapacit\u00e9 de dire si ce qu\u2019il fait, c\u2019est bien ou mal. Je ne suis pas un tribunal, je ne suis pas La Haye\u202f!\u2009\u00bb, d\u00e9clare-t-il \u00e0 Sud-Ouest \u00e0 son retour.<br \/>\nL\u2019homme de la terre, Jean Lassalle souhaite \u00ab\u2009remettre \u00e0 la mode la campagne de France, car c\u2019est le c\u0153ur du pays, et r\u00e9habiliter toutes les provinces.\u2009\u00bb Ce n\u2019est pas une blague, le d\u00e9put\u00e9 veut \u00ab\u2009mettre en avant les arts martiaux pour que les gens puissent se d\u00e9fendre.\u2009\u00bb<br \/>\n\u00ab\u2009Le pays est en train de s\u2019\u00e9crouler. Cette campagne est indigne\u2009\u00bb, expliquait-il au d\u00e9but du mois de mars en Vend\u00e9e. Si vous voulez qu\u2019on sorte de cet ennui mortel, il faut injecter du Jean Lassalle dans le turbo.\u2009\u00bb<\/p>\n<h1>Quelques morceaux choisis de Jean Lassalle<\/h1>\n<p><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/aRJKLvpQlDE\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/QnmJEHjPuIU\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/OfzWYS7ZDSA\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/i-8Grx5g10Q\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<h2>N\u2019\u00e9sitez pas \u00e0 aller sur You tube pour l\u2019\u00e9couter. Nous avons des hommes de valeur en France, c\u2019est mieux que Macron !!! Dix Mille fois mieux et Cent mille fois mieux que Fillon !!!<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Source Ouest France Le d\u00e9put\u00e9 des Pyr\u00e9n\u00e9es-Atlantiques ex-Modem Jean Lassalle, 61 ans, marcheur, chanteur, provocateur, sans \u00e9tiquette politique et sans argent, a obtenu ses 500 signatures pour \u00eatre au premier tour de la pr\u00e9sidence de la R\u00e9publique. Avec l\u2019accent rocailleux de son B\u00e9arn natal, il annon\u00e7ait, le 17 mars 2016\u2009: \u00ab\u2009Je veux \u00eatre un candidat populaire qui est l\u00e0 pour retaper la France, pour aller vers le peuple.\u2009\u00bb Jean Lassalle, il y a un an d\u00e9j\u00e0, professait que les 500 signatures ne seraient \u00ab\u2009pas un probl\u00e8me\u2009\u00bb. Et il les a eues, comme l&rsquo;a confirm\u00e9 samedi 18 mars le Conseil constitutionnel. En octobre 2016, Jean Lassalle sort un livre programme Un berger \u00e0 l\u2019Elys\u00e9e. Programm\u00e9 depuis son enfance, son chemin politique est pour lui une \u00e9vidence. \u00ab\u2009Je n\u2019ai pas un sou, mais si les gens croient en moi, je trouverai de l\u2019argent.\u2009\u00bb Sans \u00e9tiquette depuis son d\u00e9part du MoDem en 2016, o\u00f9 il est rest\u00e9 pr\u00e8s de 10 ans, il a l\u2019intention de cr\u00e9er un parti. \u00ab\u2009Le nom, je le trouverai avec le peuple\u2009\u00bb. \u00ab\u2009Mon r\u00eave c\u2019\u00e9tait d\u2019\u00eatre rugbymen.\u2009\u00bb Du haut de son 1,92\u2009m, Jean Lassalle en impose. Le rugby, il l\u2019a dans la carrure, le nez \u00e0 la Depardieu et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/6258"}],"collection":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/comments?post=6258"}],"version-history":[{"count":1,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/6258\/revisions"}],"predecessor-version":[{"id":6261,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/6258\/revisions\/6261"}],"wp:attachment":[{"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/media?parent=6258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/categories?post=6258"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/tags?post=6258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}