{"id":5886,"date":"2016-11-23T15:32:47","date_gmt":"2016-11-23T14:32:47","guid":{"rendered":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/?p=5886"},"modified":"2016-11-23T15:32:47","modified_gmt":"2016-11-23T14:32:47","slug":"primaires-bhl-avait-tout-prevu-ou-presque","status":"publish","type":"post","link":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/blog\/2016\/11\/23\/primaires-bhl-avait-tout-prevu-ou-presque\/","title":{"rendered":"Primaires : BHL avait tout pr\u00e9vu \u2013 ou presque &#8230;"},"content":{"rendered":"<p><a href=\"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/11\/Sans-titre.jpg\"><img loading=\"lazy\" src=\"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/11\/Sans-titre.jpg\" alt=\"sans-titre\" width=\"650\" height=\"445\" class=\"alignnone size-full wp-image-5887\" srcset=\"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/11\/Sans-titre.jpg 650w, https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/11\/Sans-titre-300x205.jpg 300w, https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2016\/11\/Sans-titre-175x120.jpg 175w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>Source : Sp\u00e9cialiste des questions europ\u00e9ennes, Pierre L\u00e9vy dirige la r\u00e9daction du mensuel Ruptures. Pr\u00e9c\u00e9demment, il a \u00e9t\u00e9 journaliste au sein du quotidien L\u2019Humanit\u00e9, ing\u00e9nieur et syndicaliste. Il est l\u2019auteur de deux essais et un roman. <\/p>\n<h1> Le journaliste Pierre L\u00e9vy imagine ici ironiquement les derni\u00e8res heures de Bernard-Henri L\u00e9vy avant les r\u00e9sultats des primaires de la droite.<\/h1>\n<p>Fin de dimanche paisible aux Deux Magots (l\u2019embl\u00e9matique caf\u00e9 de Saint-Germain des Pr\u00e9s, r\u00e9cemment rebaptis\u00e9 Les deux Mac Do en raison de la vague populiste qui menace de submerger la France, l\u2019Europe et le monde). Humblement assis tout au fond de la salle, Bernard-Henri L\u00e9vy \u2013 qui n\u2019aime rien tant que la discr\u00e9tion \u2013 devise avec quelques proches, auxquels s\u2019est jointe une poign\u00e9e de journalistes amis.<\/p>\n<p>Une douce chaleur enveloppe le bistro mythique, au point que le phare de la pens\u00e9e mondiale a d\u00e9fait jusqu\u2019au cinqui\u00e8me bouton de sa chemise, toujours d\u2019une immacul\u00e9e blancheur, m\u00eame quand il passe en revue les combattantes kurdes sur le front irakien. Cette d\u00e9contraction vestimentaire, confient ses amis, exprime sa modeste mani\u00e8re de protester contre le r\u00e9chauffement de la plan\u00e8te, qui est, avec le discr\u00e9dit absurde des \u00e9lites mondialis\u00e9es, l\u2019autre plaie des temps modernes.<\/p>\n<p>Tout naturellement, la conversation roule sur le premier tour des primaires \u00e0 droite, dont les r\u00e9sultats seront connus dans quelques heures. Le plus grand philosophe que la France ait connu depuis Jean-Baptiste Botul (philosophe fictif), voire Vercing\u00e9torix, est \u00e9galement un fin connaisseur de la vie politique hexagonale. Il jubile, car d\u00e9sormais, il en est s\u00fbr : ce sera Nicolas.<\/p>\n<h1>Il faut faire donner l\u2019aviation puis l\u2019infanterie fran\u00e7aise pour sauver la cit\u00e9 des griffes du boucher de Damas et de celles de son terrifiant mentor du Kremlin<\/h1>\n<p>Il a d\u2019ailleurs ce matin-l\u00e0 fait une br\u00e8ve excursion dans la p\u00e9riph\u00e9rie parisienne, du c\u00f4t\u00e9 du 16\u00e8me arrondissement, et a m\u00eame pouss\u00e9 l\u2019aventure jusqu\u2019en banlieue \u2013 \u00e0 Neuilly \u2013 sans garde du corps ni cam\u00e9ra, pour mieux se p\u00e9n\u00e9trer du sentiment populaire. Et son verdict est sans appel : l\u2019ancien chef de l\u2019Etat l\u2019emportera haut la main. Sa naturelle prudence l\u2019emp\u00eache d\u2019exprimer compl\u00e8tement sa conviction, mais il confiera en apart\u00e9 que son ami pourrait m\u00eame gagner d\u00e8s le premier tour. Or tous le savent : ses intuitions ne le trompent jamais.<\/p>\n<p>Du coup, il se laisse aller \u00e0 \u00e9voquer quelques projets qui lui tiennent \u00e0 c\u0153ur, de nature \u00e0 inverser la terrible marche du monde vers l\u2019ab\u00eeme, le redoutable triomphe de \u00abl\u2019amour du vide (et de) la haine de l\u2019autre\u00bb. Il faut tuer le pire, s\u2019enflamme-t-il \u00e0 la pens\u00e9e des nouvelles \u00e9quip\u00e9es qu\u2019il se r\u00e9jouit de pr\u00e9parer avec le mari de Carla.<\/p>\n<p>Une premi\u00e8re exp\u00e9dition s\u2019impose comme un devoir moral inspir\u00e9 des Lumi\u00e8res : venir au secours d\u2019Alep martyris\u00e9e. Il faut faire donner l\u2019aviation puis l\u2019infanterie fran\u00e7aise pour sauver la cit\u00e9 des griffes du boucher de Damas et de celles de son terrifiant mentor du Kremlin. Car le soleil des intellectuels est \u00e9galement un fin strat\u00e8ge militaire, et se rem\u00e9more non sans \u00e9motion la brillante croisade qui a permis de d\u00e9barrasser la terre du dictateur Kadhafi, et d\u2019apporter ainsi bonheur, s\u00e9r\u00e9nit\u00e9 et progr\u00e8s au peuple libyen \u2013 et \u00e0 toute la r\u00e9gion.<\/p>\n<p>Accessoirement \u2013 il s\u2019en ouvre ce soir avec gourmandise \u2013 il a d\u00e9j\u00e0 jet\u00e9 les jalons d\u2019un grand film qui retracera cette \u00e9pop\u00e9e historique destin\u00e9e \u00e0 sauver la Syrie, et pourrait m\u00eame forcer sa nature en se mettant en sc\u00e8ne, naturellement dans un humble second r\u00f4le. Apr\u00e8s Le serment de Tobrouk, qui fit trembler le box office plan\u00e9taire \u2013 85 entr\u00e9es en tout, places exo comprises \u2013 le g\u00e9nie de la pens\u00e9e et de l\u2019action r\u00eave de r\u00e9aliser Le Serment d\u2019Alep, qui pourrait aussi s\u2019appeler Terminator, le retour.<\/p>\n<p>Pour autant, sa g\u00e9n\u00e9rosit\u00e9 plan\u00e9taire tourment\u00e9e ne le laisse pas en paix. Il se fait fort de convaincre le futur pr\u00e9sident Sarkozy de capitaliser sur son prochain triomphe syrien. De mani\u00e8re entendue, il regarde son bras et prom\u00e8ne son regard alternativement sur deux points de part et d\u2019autre de celui-ci. Les familiers de Bernard-Henri ont compris : il entend signifier ainsi qu\u2019il faut franchir la Manche.<\/p>\n<p>Et venir ainsi au secours des malheureux Britanniques victimes du Brexit, en quelque sorte pris en otage par \u00abdes rebelles analphab\u00e8tes et des n\u00e9onationalistes \u00e0 sueurs froides et front de b\u0153uf\u00bb, promoteurs de la haine de l\u2019Autre \u2013 et plus particuli\u00e8rement la haine de la Finance, signe indiscutable de l\u2019antis\u00e9mitisme rampant, rappelle-t-il opportun\u00e9ment. Au nom de la \u00abboursouflure du moi\u00bb (un d\u00e9faut que le simple citoyen L\u00e9vy abhorre par-dessus tous les autres), ceux-ci ont fait triompher le \u00absouverainisme le plus rance et (le) nationalisme le plus b\u00eate\u00bb, ouvrant ainsi la perspective d\u2019une \u00abEurope qui est en train de se dissoudre dans le n\u00e9ant (du) ressentiment\u00bb.<\/p>\n<h1>D\u00e9cid\u00e9ment, BHL n\u2019a rien perdu de sa lucidit\u00e9, de son humanisme et de son \u00e9nergie. Nous voil\u00e0 rassur\u00e9s<\/h1>\n<p>Eh bien, il faut redonner la parole \u00e0 l\u2019amour et \u00e0 la raison, affirme en substance le fleuve de la pens\u00e9e du 21e si\u00e8cle. Une exp\u00e9dition militaire pourrait y pourvoir, d\u2019autant que les accords de coop\u00e9ration sign\u00e9s par l\u2019ancien et futur chef de l\u2019Etat avec la perfide Albion nous donnent acc\u00e8s \u00e0 tous ses secrets militaires. La d\u00e9mocratie y gagnerait, tant il va de soi que les Britanniques regrettent d\u00e9sormais leur vote, \u00e0 l\u2019instar des expatri\u00e9s continentaux qui ont manifest\u00e9 leur refus de voir Londres perdre son statut de ville ouverte, multiculturelle et donc europ\u00e9enne.<\/p>\n<p>A propos de manifestations, justement, le philosophe humaniste refuse qu\u2019on laisse orphelins ces protestataires am\u00e9ricains qui refusent, \u00f4 combien l\u00e9gitimement, l\u2019\u00e9lection de l\u2019\u00abantis\u00e9mite\u00bb Donald Trump. Celui-ci ne r\u00eave-t-il pas de laisser Vladimir Poutine envahir les Pays baltes et la Pologne, et de \u00abdealer\u00bb avec lui sur le Moyen-Orient ? Il faut venir au secours de cette Am\u00e9rique ouverte ! Evidemment, une nouvelle op\u00e9ration La Fayette ne serait pas une mince affaire, qui verrait le pays des droits de l\u2019Homme venir \u00e0 nouveau au secours du peuple fr\u00e8re am\u00e9ricain. Mais il se fait fort de convaincre Nico.<\/p>\n<p>Encore faut-il que celui-ci acc\u00e8de \u00e0 l\u2019Elys\u00e9e, lui fait-on doucement remarquer. Or les derniers jours de campagne sembleraient indiquer une perc\u00e9e de Fran\u00e7ois Fillon. La lumi\u00e8re de l\u2019Occident balaie d\u2019un revers de main cette hypoth\u00e8se ridicule. Ne serait-ce que parce que les \u00e9lecteurs n\u2019accepteront jamais de placer en t\u00eate un homme suspect\u00e9 de nourrir quelques intentions amicales vis-\u00e0-vis de Moscou, tranche-t-il d\u2019un ton assur\u00e9.<br \/>\nLes convives ne peuvent qu\u2019acquiescer devant une telle \u00e9vidence, confirm\u00e9e par tous les sondages.<br \/>\nDu reste, chacun le sait : la perspicacit\u00e9 et la prescience du philosophe-strat\u00e8ge-politologue-combattant n\u2019ont jamais \u00e9t\u00e9 prises en d\u00e9faut.<\/p>\n<p>D\u00e9cid\u00e9ment, BHL n\u2019a rien perdu de sa lucidit\u00e9, de son humanisme et de son \u00e9nergie. Nous voil\u00e0 rassur\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Source : Sp\u00e9cialiste des questions europ\u00e9ennes, Pierre L\u00e9vy dirige la r\u00e9daction du mensuel Ruptures. Pr\u00e9c\u00e9demment, il a \u00e9t\u00e9 journaliste au sein du quotidien L\u2019Humanit\u00e9, ing\u00e9nieur et syndicaliste. Il est l\u2019auteur de deux essais et un roman. Le journaliste Pierre L\u00e9vy imagine ici ironiquement les derni\u00e8res heures de Bernard-Henri L\u00e9vy avant les r\u00e9sultats des primaires de la droite. Fin de dimanche paisible aux Deux Magots (l\u2019embl\u00e9matique caf\u00e9 de Saint-Germain des Pr\u00e9s, r\u00e9cemment rebaptis\u00e9 Les deux Mac Do en raison de la vague populiste qui menace de submerger la France, l\u2019Europe et le monde). Humblement assis tout au fond de la salle, Bernard-Henri L\u00e9vy \u2013 qui n\u2019aime rien tant que la discr\u00e9tion \u2013 devise avec quelques proches, auxquels s\u2019est jointe une poign\u00e9e de journalistes amis. Une douce chaleur enveloppe le bistro mythique, au point que le phare de la pens\u00e9e mondiale a d\u00e9fait jusqu\u2019au cinqui\u00e8me bouton de sa chemise, toujours d\u2019une immacul\u00e9e blancheur, m\u00eame quand il passe en revue les combattantes kurdes sur le front irakien. Cette d\u00e9contraction vestimentaire, confient ses amis, exprime sa modeste mani\u00e8re de protester contre le r\u00e9chauffement de la plan\u00e8te, qui est, avec le discr\u00e9dit absurde des \u00e9lites mondialis\u00e9es, l\u2019autre plaie des temps modernes. Tout naturellement, la conversation [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/5886"}],"collection":[{"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/comments?post=5886"}],"version-history":[{"count":1,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/5886\/revisions"}],"predecessor-version":[{"id":5888,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/5886\/revisions\/5888"}],"wp:attachment":[{"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/media?parent=5886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/categories?post=5886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/tags?post=5886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}