{"id":6465,"date":"2017-06-12T10:17:14","date_gmt":"2017-06-12T08:17:14","guid":{"rendered":"http:\/\/saint-andre-d-olerargues.com\/wpdossier\/?p=6465"},"modified":"2017-06-12T10:20:11","modified_gmt":"2017-06-12T08:20:11","slug":"vu-de-suisse-une-semaine-a-regarder-la-fange-televisuelle-francaise","status":"publish","type":"post","link":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/blog\/2017\/06\/12\/vu-de-suisse-une-semaine-a-regarder-la-fange-televisuelle-francaise\/","title":{"rendered":"Vu de Suisse. Une semaine \u00e0 regarder la fange t\u00e9l\u00e9visuelle fran\u00e7aise"},"content":{"rendered":"<p><a href=\"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/06\/Le-temps.jpg\"><img loading=\"lazy\" src=\"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/06\/Le-temps.jpg\" alt=\"\" width=\"605\" height=\"239\" class=\"alignnone size-full wp-image-6466\" srcset=\"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/06\/Le-temps.jpg 605w, https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/06\/Le-temps-300x119.jpg 300w, https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-content\/uploads\/2017\/06\/Le-temps-304x120.jpg 304w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/><\/a><br \/>\nSource : Alain Campiotti  Le Temps  Lausanne  www.letemps.ch<\/p>\n<h1>Intrigu\u00e9 par l\u2019affaire Hanouna, un journaliste suisse s\u2019est risqu\u00e9 \u00e0 observer les cha\u00eenes fran\u00e7aises pendant sept jours. <\/h1>\n<p>Il d\u00e9couvre, atterr\u00e9, un m\u00e9lange de vulgarit\u00e9, de r\u00e9alit\u00e9 trafiqu\u00e9e et d\u2019imposture.<br \/>\nIl y a quelques jours, on m\u2019a invit\u00e9 \u00e0 plonger dans un monde pour moi \u00e9trange et inconnu : le nouveau paysage audiovisuel fran\u00e7ais. Un cloaque. Pourquoi moi, zappeur vieillissant\u2009? Parce que je ne suis plus dommage\u2009? \u201cVa, tant qu\u2019il est temps, et d\u00e9couvre cette t\u00e9l\u00e9vision dont on parle\u2009!\u201d J\u2019ai eu le malheur d\u2019accepter. C\u2019est un cloaque.<br \/>\nLa proposition avait une origine : tout ce bruit autour de TPMP. Maintenant, je sais traduire : Touche Pas \u00e0 Mon Poste (C8). J\u2019ai saut\u00e9 dans la galaxie Hanouna, et ce n\u2019est pas joli \u00e0 voir, ni agr\u00e9able \u00e0 sentir. Naturellement, depuis qu\u2019une menace de sanction plane sur son contrat de 50 millions d\u2019euros l\u2019an, l\u2019animateur barbu, vocif\u00e9rant et hyst\u00e9rique \u2013 Cyril de son pr\u00e9nom \u2013 montre un poil de prudence : il ne se risquera pas de sit\u00f4t \u00e0 humilier, comme il l\u2019a fait \u00e0 la mi-mai, un jeune gay en se faisant passer, au t\u00e9l\u00e9phone, devant la France enti\u00e8re, pour le client d\u2019un site de rencontres\u2009; son complice et patron, Vincent Bollor\u00e9, rustre milliardaire, ne veut pas mettre en p\u00e9ril son empire digital en construction.<\/p>\n<h1>Hanouna ou le vertige de la vulgarit\u00e9<\/h1>\n<p>Ces petites pr\u00e9cautions dict\u00e9es par l\u2019incident homophobe ne changent pourtant rien au fond : TPMP est en permanence une entreprise obsc\u00e8ne et rentable de d\u00e9cervelage. Mais en \u00e9crivant cela, un grand trouble me prend. Plus de 1 million de francophones regardent chaque jour ce spectacle d\u00e9gradant. Que pensent-ils, tous ces \u201cch\u00e9ris\u201d, comme les nomme (moi donc y compris) Hanouna, quand un de ses comparses raconte qu\u2019il a piss\u00e9 sur la voiture d\u2019un ami, et qu\u2019un autre s\u2019esclaffe en disant qu\u2019il a p\u00e9t\u00e9 dans la loge de sa voisine \u2013 charm\u00e9e : \u201cpet avou\u00e9 est \u00e0 moiti\u00e9 pardonn\u00e9\u201d\u2009?<br \/>\n\u00c9coutent-ils volontiers ce duplex avec Los Angeles, dans un brouhaha tel qu\u2019on ne saisit de la conversation que quelques mots, comme \u201cconnard\u201d ou, pour conclure, \u201con ne va pas faire chier toute la France\u2009?\u201d Rient-ils quand Hanouna se roule sur sa table en poussant de petits cris de poulet qu\u2019on \u00e9gorge\u2009? Ou quand un de ses faire-valoir, parlant d\u2019un village du Lot, lui demande : \u201cTu as vu Montcuq\u2009?\u201d Ou quand Baba (c\u2019est aussi son nom) fait venir de petits enfants dress\u00e9s comme des singes pour participer \u00e0 ses absurdit\u00e9s, et qu\u2019il les embrasse sans retenue\u2009?<br \/>\nCe ne sont que des questions \u00e9tonn\u00e9es, mais elles donnent le vertige. Les centaines de milliers de fid\u00e8les de TPMP (la meilleure audience dans le genre) donnent au syst\u00e8me naus\u00e9abond le carburant n\u00e9cessaire \u00e0 son bon fonctionnement : malgr\u00e9 le hiatus homophobe, ils aimantent par leur nombre la pub, de Suisse massivement (Migros, Coop\u2026), qui incite Baba et sa bande, puisque \u00e7a paie, \u00e0 en remettre quelques louches dans la vulgarit\u00e9.<br \/>\nOn voit bien le pouvoir s\u00e9ducteur de cette sorte de d\u00e9vergondage fangeux, quand l\u2019irrespect s\u2019en m\u00eale, quand les normes sont largu\u00e9es, quand la provocation se lib\u00e8re dans l\u2019insouciance. C\u2019est ce qui donne sa p\u00e9tulance au talk-show tel qu\u2019il est pratiqu\u00e9 aux \u00c9tats-Unis, o\u00f9 j\u2019ai s\u00e9journ\u00e9 durant six ans. Mais en traversant l\u2019Atlantique, le genre s\u2019est d\u00e9grad\u00e9, ab\u00e2tardi, il a \u00e9t\u00e9 souill\u00e9 et abaiss\u00e9. D\u2019or \u00e0 New York (Letterman, Stewart, Colbert\u2026), il est devenu plomb tremp\u00e9 dans la boue par Cyril Hanouna, avec un palier interm\u00e9diaire quand Thierry Ardisson demandait au malheureux Michel Rocard \u201csi sucer c\u2019est tromper\u201d.<br \/>\nLe plus d\u00e9concertant dans TPMP, c\u2019est que l\u2019unique sujet de discussion de Baba et des siens, c\u2019est eux-m\u00eames, leurs amis et leurs ennemis dans le cirque audiovisuel parisien. Ainsi, l\u2019autre soir, les \u201cpas toucheurs\u201d ironisaient sur je ne sais plus quelle blonde des Anges.<\/p>\n<h1>Les Anges de la t\u00e9l\u00e9r\u00e9alit\u00e9, \u00e9loge du vide<\/h1>\n<p>Les Anges, Back to Paradise (NRJ12)\u2009! Neuvi\u00e8me saison\u2009! Une villa \u00e0 Miami\u2009! Les Anges, c\u2019est l\u2019artifice imb\u00e9cile \u00e9lev\u00e9 au niveau sup\u00e9rieur des beaux-arts, c\u2019est le stade ultime de la t\u00e9l\u00e9-r\u00e9alit\u00e9 lobotomis\u00e9e, non pas une ou deux heures par jour, mais \u00e0 journ\u00e9e faite pour qui peut supporter une chose pareille. Vous connaissez le principe\u2009? Les h\u00f4tes de la villa sont des filles et des gars, tous format\u00e9s, s\u00e9lectionn\u00e9s dans d\u2019autres \u00e9missions fran\u00e7aises du m\u00eame acabit. La cr\u00e8me de la cr\u00e8me, donc. Ils vivent l\u00e0, dans le luxe, entre la piscine et de larges sofas blancs o\u00f9 ils s\u2019affalent parce qu\u2019ils sont soit superfatigu\u00e9s, soit hypercontents d\u2019\u00eatre all\u00e9s dans un restaurant hypersympa o\u00f9 ils ont bu, avant de danser, des cocktails dans des verres hauts comme des vases \u00e0 tulipe.<br \/>\nQue font-ils\u2009? Rien. Ils ach\u00e8tent des fringues, pr\u00e9parent des castings pour acc\u00e9der \u00e0 un niveau encore plus \u00e9lev\u00e9 de vacuit\u00e9. Le sc\u00e9nario leur fait jouer des flirts byzantins et asexu\u00e9s, et des querelles risibles qui poussent une fille \u00e0 dire que \u00e7a lui \u201cmet la haine\u201d et qu\u2019elle va \u201crester au lit\u201d. S\u2019il y avait une censure en France \u2013 qu\u2019aux dieux ne plaise\u2009! \u2013 elle aurait l\u00e0 son premier devoir. En fait, Les Anges sont \u201cd\u00e9conseill\u00e9s aux moins de 10 ans\u201d. Autant dire qu\u2019\u00e0 11 on peut entrer dans cet apprentissage de l\u2019insignifiance la plus radicale.<br \/>\nAu d\u00e9but de la semaine, Hanouna et ses z\u00e8bres, dans l\u2019exploration de leur territoire de chasse, s\u2019\u00e9taient aussi int\u00e9ress\u00e9s, \u00e0 leur mani\u00e8re, \u00e0 Koh Lanta (TF1, audience outrageusement sup\u00e9rieure) parce qu\u2019ils avaient remarqu\u00e9 que Cl\u00e9mentine, l\u2019une des h\u00e9ro\u00efnes de cette aventure, n\u2019avait pas ras\u00e9 ses poils sous les aisselles, et \u00e0 The Island (M6), autre exp\u00e9dition qu\u2019ils trouvent longuette et ennuyeuse. Et c\u2019est bien int\u00e9ressant.<\/p>\n<h1>The Island, un poil de sinc\u00e9rit\u00e9 sur M6<\/h1>\n<p>Car The Island, dans l\u2019univers frelat\u00e9 de la t\u00e9l\u00e9r\u00e9alit\u00e9, fait exception : les aventuriers de Mike Horn, dans leur archipel du Pacifique, sont les seuls \u00e0 qui on peut croire un peu. Quand Thibaud l\u2019unijambiste parle de ses \u00e9preuves, il respire la sinc\u00e9rit\u00e9. Quand Claire dit qu\u2019elle n\u2019en peut plus, on voit son \u00e9puisement. Et quand ils fabriquent un radeau pour traverser un bras de mer parmi les crocodiles, on comprend que l\u2019\u00e9preuve n\u2019est pas simple. Koh Lanta, de son c\u00f4t\u00e9, est aussi \u00e9loign\u00e9 de toute vie r\u00e9elle que Les Anges, sans la villa et les sofas blancs, et c\u2019est sans doute ce qui pla\u00eet \u00e0 la bande excit\u00e9e de TPMP : Mathilde met le collier qui va lui sauver la mise dans sa culotte, et on a l\u2019impression de lire avec elle le sc\u00e9nario cucul qui lui a \u00e9t\u00e9 pr\u00e9par\u00e9.<\/p>\n<h1>Cultivons la m\u00e9diocrit\u00e9 avec Bienvenue au Camping<\/h1>\n<p>Pour me reposer de ces aventures lointaines, je suis revenu en terre famili\u00e8re : Bienvenue au Camping (TF1). C\u2019est un rude retour vers le r\u00e9el, et un autre pan de la t\u00e9l\u00e9vision populaire. Cette \u00e9cole-l\u00e0 pourrait s\u2019intituler : cultivons \u00e0 quatre notre m\u00e9diocrit\u00e9. Au Camping, trois propri\u00e9taires d\u2019installations de mobile home ou de cabanons visitent, \u00e0 tour de r\u00f4le, celle d\u2019un quatri\u00e8me et le notent. \u00c0 la fin de la semaine, il y a un vainqueur. Entre-temps, c\u2019est un festival de petites d\u00e9licatesses : examen de matelas ou de chiottes, karaok\u00e9 ou danse des canards le soir venu, qualit\u00e9 des frites \u201cpas maison\u201d, bilan de la journ\u00e9e sur l\u2019oreiller et ronflements en direct, sans oublier \u201cT\u2019as pas lav\u00e9 tes panards\u201d\u2009; et il faut apporter ses couverts\u2009!<\/p>\n<h1>Un d\u00eener presque parfait et parfois dr\u00f4le<\/h1>\n<p>Le m\u00eame canevas s\u2019applique \u00e0 diff\u00e9rentes situations, \u00e0 table ou \u00e0 la noce. Dans Un d\u00eener presque parfait (M6), trois cuisiniers amateurs s\u2019invitent chez un quatri\u00e8me, et c\u2019est parfois dr\u00f4le. Dans Quatre Mariages pour une lune de miel (TF1), trois futures ou tout juste \u00e9pouses jaugent la noce d\u2019une quatri\u00e8me, du faire-part \u00e0 l\u2019alliance, en passant par les bonbons dispos\u00e9s en c\u0153ur, avec un Sinatra langoureux tombant du haut-parleur. \u201cTrop mignon\u201d : elles le disent.<\/p>\n<h1>Aux fronti\u00e8res du r\u00e9el avec Super Nanny<\/h1>\n<p>C\u2019\u00e9tait le rayon du r\u00e9el tout cru. \u00c0 c\u00f4t\u00e9, il y a celui de la r\u00e9alit\u00e9 trafiqu\u00e9e : une situation familiale \u00e0 peu pr\u00e8s d\u00e9sesp\u00e9r\u00e9e, et un sauveur qui frappe \u00e0 la porte, avec ses cam\u00e9ras. Dans Super Nanny (NT1), Sylvie Jenaly, ancienne \u00e9tudiante de l\u2019\u00c9cole h\u00f4teli\u00e8re de Lausanne, tailleur noir et sac rouge, contemple d\u2019un air attrist\u00e9 le bordel qui r\u00e8gne \u00e0 la table de Cyril (un autre) et Fallon qui ne contr\u00f4lent plus leurs quatre enfants, ou avec une moue encore plus navr\u00e9e Sabrina en train de donner le sein \u00e0 sa fille de 3 ans pour la calmer. \u201cOn va r\u00e9\u00e9quilibrer un peu tout \u00e7a\u201d, intervient la nanny, et elle expose \u00e0 la maisonn\u00e9e rassembl\u00e9e leurs nouvelles r\u00e8gles de vie sur un grand \u00e9cran. \u00c0 la fin, tout le monde \u00e0 la larme \u00e0 l\u2019\u0153il.<\/p>\n<h1>Le spectacle du malheur sur NRJ12<\/h1>\n<p>Dans SOS : ma famille a besoin d\u2019aide (NRJ12), Pascal Soetens, le \u201cgrand fr\u00e8re\u201d, affronte des situations encore plus cors\u00e9es. Eric et Evelyne abusent visiblement du ros\u00e9, et Aur\u00e9lien, qui en est \u00e0 son troisi\u00e8me p\u00e8re, est d\u00e9j\u00e0 pass\u00e9 par l\u2019alcool, lui aussi, et par la prison. Dans la famille, \u00e7a cogne, et le grand fiston se r\u00e9fugie du soir au matin devant sa console de jeux vid\u00e9o. D\u00e9sesp\u00e9r\u00e9. Soetens embarque toute la maisonn\u00e9e vers un cabanon (retour au Camping\u2009!) en pleine nature, sans \u00e9cran et sans bouteille. Il leur fait casser des briques, propose \u00e0 Aur\u00e9lien un peu de culture physique et du parapente. Au final, tout le monde s\u2019embrasse.<br \/>\nQue se passe-t-il six mois, un ou deux ans plus tard\u2009? On ne le sait pas. Des drames et des trag\u00e9dies transform\u00e9s en spectacles, des malheureux \u00e0 qui on demande de rejouer leur propre mis\u00e8re mise en sc\u00e8ne devant la cam\u00e9ra : c\u2019est bien s\u00fbr une imposture.<br \/>\nDans un entretien qu\u2019il a donn\u00e9 au Figaro, on comprend que le \u201cgrand fr\u00e8re\u201d n\u2019est pas exactement un travailleur social. Interrog\u00e9 au sujet de Cyril Hanouna, Soetens r\u00e9pond que c\u2019est son mod\u00e8le : \u201cJ\u2019aimerais me calquer sur lui.\u201d La boucle est ainsi boucl\u00e9e. Et comme dit Baba dans un \u00e9change compulsif avec un de ses meilleurs ennemis (Yann Barthes) : \u201cOn s\u2019en bat les couilles.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Source : Alain Campiotti Le Temps Lausanne www.letemps.ch Intrigu\u00e9 par l\u2019affaire Hanouna, un journaliste suisse s\u2019est risqu\u00e9 \u00e0 observer les cha\u00eenes fran\u00e7aises pendant sept jours. Il d\u00e9couvre, atterr\u00e9, un m\u00e9lange de vulgarit\u00e9, de r\u00e9alit\u00e9 trafiqu\u00e9e et d\u2019imposture. Il y a quelques jours, on m\u2019a invit\u00e9 \u00e0 plonger dans un monde pour moi \u00e9trange et inconnu : le nouveau paysage audiovisuel fran\u00e7ais. Un cloaque. Pourquoi moi, zappeur vieillissant\u2009? Parce que je ne suis plus dommage\u2009? \u201cVa, tant qu\u2019il est temps, et d\u00e9couvre cette t\u00e9l\u00e9vision dont on parle\u2009!\u201d J\u2019ai eu le malheur d\u2019accepter. C\u2019est un cloaque. La proposition avait une origine : tout ce bruit autour de TPMP. Maintenant, je sais traduire : Touche Pas \u00e0 Mon Poste (C8). J\u2019ai saut\u00e9 dans la galaxie Hanouna, et ce n\u2019est pas joli \u00e0 voir, ni agr\u00e9able \u00e0 sentir. Naturellement, depuis qu\u2019une menace de sanction plane sur son contrat de 50 millions d\u2019euros l\u2019an, l\u2019animateur barbu, vocif\u00e9rant et hyst\u00e9rique \u2013 Cyril de son pr\u00e9nom \u2013 montre un poil de prudence : il ne se risquera pas de sit\u00f4t \u00e0 humilier, comme il l\u2019a fait \u00e0 la mi-mai, un jeune gay en se faisant passer, au t\u00e9l\u00e9phone, devant la France enti\u00e8re, pour le client d\u2019un site [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/6465"}],"collection":[{"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/comments?post=6465"}],"version-history":[{"count":1,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/6465\/revisions"}],"predecessor-version":[{"id":6467,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/posts\/6465\/revisions\/6467"}],"wp:attachment":[{"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/media?parent=6465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/categories?post=6465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-andre-d-olerargues.com\/wpdossier\/wp-json\/wp\/v2\/tags?post=6465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}